{"id":2800,"date":"2023-11-03T02:15:22","date_gmt":"2023-11-03T02:15:22","guid":{"rendered":"https:\/\/metzineres.org\/metziagenda-of-november-2023\/"},"modified":"2025-01-17T02:17:09","modified_gmt":"2025-01-17T02:17:09","slug":"metziagenda-de-novembre-2023","status":"publish","type":"post","link":"http:\/\/metzineres.org\/ca\/metziagenda-de-novembre-2023\/","title":{"rendered":"Metziagenda de novembre 2023"},"content":{"rendered":"<p>Calendari d&#8217;activitats setmanals per a lxs participants de Metzineres. Aquest mes tenim:<\/p>\n<ul>\n<li>Costura guerrilla amb\u00a0Franche PuntadaLibre i Sindillar<\/li>\n<li>Reunions de la XADUD (Xarxa de Donxs que Usen Drogues), a l&#8217;Ateneu del Raval<\/li>\n<li>Assemblea<\/li>\n<li>Prente&#8217;l Pel: Perruqueria amb la Nani<\/li>\n<li>Reunions DIRD (Donxs Impulsores de Reducci\u00f3 de Danys)<\/li>\n<li>Monologueando<\/li>\n<li>Dinar comunitari<\/li>\n<li>Activitat externa: Sortides i excursions<\/li>\n<li>Kosmetikin: Taller de cosm\u00e8tica natural<\/li>\n<li>Metzituning: Ens posem guapxs juntxs!<\/li>\n<li>Crispelis:\u00a0Crispetes + pel\u00b7lis!<\/li>\n<\/ul>\n<p>Activitats especials de novembre:<\/p>\n<ul>\n<li>Diumenge 5:\u00a0MetziParadeta al Fleadonia Market<\/li>\n<li>Divendres 10: Presentaci\u00f3 del video &#8216;Support Don&#8217;t Punish 2023&#8217; i de l&#8217;Almanac Ut\u00f2pic amb Christina Schultz al Festival Cultura Raval(s)<\/li>\n<li>Dilluns 20: Dia Internacional de la Mem\u00f2ria Trans<\/li>\n<li>Dijous 23: Dia de les Persones sense Llar<\/li>\n<li>Divendres 24: Manifestaci\u00f3 nocturna No-mixta contra les viol\u00e8ncies masclistes<\/li>\n<li>Dissabte 25: Manifestaci\u00f3 unit\u00e0ria contra les viol\u00e8ncies masclistes<\/li>\n<li>Del 25\/11 al 10\/11: 16 dies d&#8217;acci\u00f3 per eliminar la viol\u00e8ncia contra les dones que usen drogues (Campanya d&#8217;EVAWUD)<\/li>\n<\/ul>\n<p>A m\u00e9s, sempre disponible:<\/p>\n<ul>\n<li>MetziSpa<\/li>\n<li>Taller de Naloxona express<\/li>\n<li>Acompanyament sanitari, social i educatiu<\/li>\n<li>Dormir de dia<\/li>\n<li>Rober, dutxa i rentadora<\/li>\n<li>Ordinadors i Internet<\/li>\n<li>ArtiSana: Espai d&#8217;artter\u00e0pia<\/li>\n<\/ul>\n<p>Horari:<\/p>\n<ul>\n<li>Dilluns, dimecres, dijous, divendres* i dissabte de 14 a 21h<\/li>\n<li>Dimarts de 18 a 21h<\/li>\n<li>Diumenge tancat<\/li>\n<\/ul>\n<p>*Els divendres a partir de les 18h farem sortides i excursions fora del local!<\/p>\n<p>Adre\u00e7a del local de Metzineres:<br \/>\nCarrer de la Lluna, 3<br \/>\nBarri del Raval (Barcelona)<\/p>\n<p>Adre\u00e7a de l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez:<br \/>\nCarrer de l&#8217;Aurora, 13<br \/>\nBarri del Raval (Barcelona)<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/metzineres.net\/imgdata\/Novembre_FINAL__2.png\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Calendari d&#8217;activitats setmanals per a lxs participants de Metzineres. Aquest mes tenim: Costura guerrilla amb\u00a0Franche PuntadaLibre i Sindillar Reunions de la XADUD (Xarxa de Donxs que Usen Drogues), a l&#8217;Ateneu del Raval Assemblea Prente&#8217;l Pel: Perruqueria amb la Nani Reunions DIRD (Donxs Impulsores de Reducci\u00f3 de Danys) Monologueando Dinar comunitari Activitat externa: Sortides i excursions [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[57],"tags":[],"class_list":["post-2800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicacions"],"_links":{"self":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/2800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/comments?post=2800"}],"version-history":[{"count":1,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/2800\/revisions"}],"predecessor-version":[{"id":2801,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/2800\/revisions\/2801"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/media\/2795"}],"wp:attachment":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/media?parent=2800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/categories?post=2800"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/tags?post=2800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}