{"id":3090,"date":"2023-01-02T03:16:42","date_gmt":"2023-01-02T03:16:42","guid":{"rendered":"https:\/\/metzineres.org\/metziagenda-of-january-2023\/"},"modified":"2025-01-17T03:17:59","modified_gmt":"2025-01-17T03:17:59","slug":"metziagenda-de-gener-2023","status":"publish","type":"post","link":"http:\/\/metzineres.org\/ca\/metziagenda-de-gener-2023\/","title":{"rendered":"MetziAgenda de Gener 2023"},"content":{"rendered":"<div class=\"post-prev-text\">\n<div class=\"post-prev-text\">\n<p>Calendari d&#8217;activitats setmanals per a lxs participants de Metzineres. Aquest mes tenim:<\/p>\n<ul>\n<li>Costura guerrillera<\/li>\n<li>Taller de Fanzine amb la Yolanda del MACBA<\/li>\n<li>Reunions de la XADUD (Xarxa de Donxs que Usen Drogues), a l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez<\/li>\n<li>Mani-cura<\/li>\n<li>Prente&#8217;l Pel: Perruqueria amb la Nani<\/li>\n<li>Autodefensa transfeminista<\/li>\n<li>Kosmetikin: Taller de cosm\u00e8tica natural<\/li>\n<li>Assemblea<\/li>\n<li>Reunions DIRD (Donxs Impulsores de Reducci\u00f3 de Danys)<\/li>\n<li>Monologueando: Taller de mon\u00f2legs, amb Vidda Priego<\/li>\n<li>Pa&#8217;Ella: La paella dels divendres a l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez<\/li>\n<li>Crispelis: Pelis i crispetes!<\/li>\n<\/ul>\n<p>Activitats especials de gener:<\/p>\n<ul>\n<li>Diumenge 15: Paradeta de Metzineres al Flead\u00f2nia Market<\/li>\n<li>Divendres 20: MetziRadio<\/li>\n<\/ul>\n<p>A m\u00e9s, sempre disponible:<\/p>\n<ul>\n<li>MetziSpa<\/li>\n<li>Taller de Naloxona\u00a0express<\/li>\n<li>Acompanyament sanitari, social i educatiu<\/li>\n<li>Dormir de dia<\/li>\n<li>Rober, dutxa i rentadora<\/li>\n<li>Ordinadors i Internet<\/li>\n<li>ArtiSana: Espai d&#8217;artter\u00e0pia<\/li>\n<\/ul>\n<p>Horari:<\/p>\n<ul>\n<li>Dilluns, dimecres, dijous, divendres* i dissabte de 14 a 21h.<\/li>\n<li>Dimarts de 16 a 21h.<\/li>\n<li>Diumenge tancat.<\/li>\n<\/ul>\n<p>*Els divendres estem fent la nostra Pa&#8217;Ella a l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez des del migdia fins a les 17h, aprox. Despr\u00e9s, anem cap al local.<\/p>\n<p>Adre\u00e7a del local de Metzineres:<br \/>\nCarrer de la Lluna, 3<br \/>\nBarri del Raval (Barcelona)<\/p>\n<p>Adre\u00e7a de l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez:<br \/>\nCarrer de l&#8217;Aurora, 13<br \/>\nBarri del Raval (Barcelona)<\/p>\n<\/div>\n<div class=\"post-prev-more-cont clearfix\">\n<div class=\"post-prev-more left\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Calendari d&#8217;activitats setmanals per a lxs participants de Metzineres. Aquest mes tenim: Costura guerrillera Taller de Fanzine amb la Yolanda del MACBA Reunions de la XADUD (Xarxa de Donxs que Usen Drogues), a l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez Mani-cura Prente&#8217;l Pel: Perruqueria amb la Nani Autodefensa transfeminista Kosmetikin: Taller de cosm\u00e8tica natural Assemblea Reunions DIRD (Donxs [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[57],"tags":[],"class_list":["post-3090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicacions"],"_links":{"self":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/3090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/comments?post=3090"}],"version-history":[{"count":1,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/3090\/revisions"}],"predecessor-version":[{"id":3091,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/3090\/revisions\/3091"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/media\/3085"}],"wp:attachment":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/media?parent=3090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/categories?post=3090"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/tags?post=3090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}