{"id":3135,"date":"2022-11-02T03:28:27","date_gmt":"2022-11-02T03:28:27","guid":{"rendered":"https:\/\/metzineres.org\/metziagenda-of-november-2022\/"},"modified":"2025-01-17T03:29:54","modified_gmt":"2025-01-17T03:29:54","slug":"metziagenda-de-novembre-2022","status":"publish","type":"post","link":"http:\/\/metzineres.org\/ca\/metziagenda-de-novembre-2022\/","title":{"rendered":"MetziAgenda de Novembre 2022"},"content":{"rendered":"<div class=\"post-prev-text\">\n<p>Calendari d&#8217;activitats setmanals per a lxs participants de Metzineres. Aquest mes tenim:<\/p>\n<ul>\n<li>Costura guerrillera<\/li>\n<li>Taller de Fanzine<\/li>\n<li>Reunions de la XADUD (Xarxa de Donxs que Usen Drogues), a l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez<\/li>\n<li>Kosmetik\u00edn: Taller de cosm\u00e8tica natural<\/li>\n<li>Autodefensa feminista<\/li>\n<li>Assemblea<\/li>\n<li>Reunions DIRD (Donxs Impulsores de Reducci\u00f3 de Danys)<\/li>\n<li>Prente&#8217;l Pel: Perruqueria amb la Nani<\/li>\n<li>Monologueando: Taller de mon\u00f2legs, amb Vidda Priego<\/li>\n<li>Pa&#8217;Ella: La paella dels divendres a l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez<\/li>\n<li>MetziRadio a l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez (quinzenal)<\/li>\n<li>Cabaret (quinzenal)<\/li>\n<li>Crispelis: Pelis i crispetes!<\/li>\n<\/ul>\n<p>Activitats especials de novembre:<\/p>\n<ul>\n<li>Diumenge 6: Flea Market<\/li>\n<li>Diumenge 20: Dia Internacional de\u00a0la Mem\u00f2ria Trans<\/li>\n<li>Dimecres 23: Dia Internacional de les Persones Sense Llar<\/li>\n<li>Divendres 25: Dia Internacional\u00a0d&#8217;Eliminaci\u00f3 de la Viol\u00e8ncia Vers les Donxs, i tret de sortida de la campanya #16Days<\/li>\n<\/ul>\n<p>A m\u00e9s, sempre disponible:<\/p>\n<ul>\n<li>MetziSpa<\/li>\n<li>Taller de Naloxona\u00a0express<\/li>\n<li>Acompanyament sanitari, social i educatiu<\/li>\n<li>Dormir de dia<\/li>\n<li>Rober, dutxa i rentadora<\/li>\n<li>Ordinadors i Internet<\/li>\n<li>ArtiSana: Espai d&#8217;artter\u00e0pia<\/li>\n<\/ul>\n<p>Horari:<\/p>\n<ul>\n<li>Dilluns, dimecres, dijous, divendres* i dissabte de 14 a 21h.<\/li>\n<li>Dimarts de 16 a 21h.<\/li>\n<li>Diumenge tancat.<\/li>\n<\/ul>\n<p>*Els divendres estem fent la nostra Pa&#8217;Ella a l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez des del migdia fins a les 17h, aprox. Despr\u00e9s, anem cap al local.<\/p>\n<p>Adre\u00e7a del local de Metzineres:<br \/>\nCarrer de la Lluna, 3<br \/>\nBarri del Raval (Barcelona)<\/p>\n<p>Adre\u00e7a de l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez:<br \/>\nCarrer de l&#8217;Aurora, 13<br \/>\nBarri del Raval (Barcelona)<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Calendari d&#8217;activitats setmanals per a lxs participants de Metzineres. Aquest mes tenim: Costura guerrillera Taller de Fanzine Reunions de la XADUD (Xarxa de Donxs que Usen Drogues), a l&#8217;\u00c0gora Juan Andr\u00e9s Ben\u00edtez Kosmetik\u00edn: Taller de cosm\u00e8tica natural Autodefensa feminista Assemblea Reunions DIRD (Donxs Impulsores de Reducci\u00f3 de Danys) Prente&#8217;l Pel: Perruqueria amb la Nani Monologueando: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[57],"tags":[],"class_list":["post-3135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicacions"],"_links":{"self":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/3135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/comments?post=3135"}],"version-history":[{"count":1,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/3135\/revisions"}],"predecessor-version":[{"id":3136,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/3135\/revisions\/3136"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/media\/3130"}],"wp:attachment":[{"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/media?parent=3135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/categories?post=3135"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/tags?post=3135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}