{"id":2780,"date":"2023-11-20T02:11:15","date_gmt":"2023-11-20T02:11:15","guid":{"rendered":"https:\/\/metzineres.org\/almanaque-utopico\/"},"modified":"2025-01-17T02:14:58","modified_gmt":"2025-01-17T02:14:58","slug":"almanaque-utopico","status":"publish","type":"post","link":"http:\/\/metzineres.org\/en\/almanaque-utopico\/","title":{"rendered":"Almanaque Ut\u00f3pico"},"content":{"rendered":"<p>Desde Metzineres, en colaboraci\u00f3n con el artista Christina Schultz, tenemos el inmenso placer de presentaros nuestro \u00faltimo proyecto: el\u00a0<strong>Almanaque Ut\u00f3pico.<\/strong><\/p>\n<p>Un almanaque es un calendario, una enciclopedia popular, una gu\u00eda pr\u00e1ctica y po\u00e9tica. En nuestro caso hemos decidido elaborar un calendario \u2018visionario\u2019 para los pr\u00f3ximos 50 a\u00f1os\u00a0<strong>donde compartimos recetas \u2018sin cocina\u2019, refranes ravaleros, collages, acontecimientos celestiales del Mediterr\u00e1neo, fechas importantes para nosotrxs y otros saberes para afrontar la vida cotidiana.<\/strong><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/metzineres.net\/imgdata\/almanac_utopic_1.jpg\" \/><\/p>\n<p>Las visiones y predicciones del futuro que aparecen en \u00e9l pretenden participar en nuestro destino y, as\u00ed, influir en el curso de la vida, incluyendo aquellxs que viven a los m\u00e1rgenes, en la l\u00ednea fronteriza.<\/p>\n<p>Cambiar los nombres de los meses del actual calendario en el Almanaque Ut\u00f3pico es el resultado de una reflexi\u00f3n sobre el origen de nuestras medidas de tiempos, planetarias y pol\u00edticas, y una adaptaci\u00f3n a las cosas que queremos honorar desde las Metzineres.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/metzineres.net\/imgdata\/almanac_utpic_3.jpg\" \/><\/p>\n<p><strong>Este proyecto se contextualiza en el barrio del Raval<\/strong>. Creemos que este barrio, con su tradici\u00f3n centenaria de varias formas de cuidados hacia las personas vulnerabilizadas, merece un trato especial de atenci\u00f3n y apoyo. Por eso, en nuestro almanaque queremos destacar los valores y peculiaridades humanistas de este barrio.<\/p>\n<p>Todo esto ha sido creado a partir de la pr\u00e1ctica del collage por parte de lxs participantxs y trabajadorxs de Metzineres junto con el artista Christina Schultz. Esperamos, sinceramente, que este almanaque sea para ti\u00a0<strong>un punto de apoyo,\u00a0lleno de esperanza y humor.<\/strong><\/p>\n<p><strong>[Pr\u00f3ximamente disponible en nuestra tienda\u00a0online de La Zona en castellano y catal\u00e1n]<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde Metzineres, en colaboraci\u00f3n con el artista Christina Schultz, tenemos el inmenso placer de presentaros nuestro \u00faltimo proyecto: el\u00a0Almanaque Ut\u00f3pico. Un almanaque es un calendario, una enciclopedia popular, una gu\u00eda pr\u00e1ctica y po\u00e9tica. En nuestro caso hemos decidido elaborar un calendario \u2018visionario\u2019 para los pr\u00f3ximos 50 a\u00f1os\u00a0donde compartimos recetas \u2018sin cocina\u2019, refranes ravaleros, collages, acontecimientos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2778,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[53],"tags":[],"class_list":["post-2780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publications"],"_links":{"self":[{"href":"http:\/\/metzineres.org\/en\/wp-json\/wp\/v2\/posts\/2780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metzineres.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/metzineres.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/metzineres.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/metzineres.org\/en\/wp-json\/wp\/v2\/comments?post=2780"}],"version-history":[{"count":1,"href":"http:\/\/metzineres.org\/en\/wp-json\/wp\/v2\/posts\/2780\/revisions"}],"predecessor-version":[{"id":2781,"href":"http:\/\/metzineres.org\/en\/wp-json\/wp\/v2\/posts\/2780\/revisions\/2781"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/metzineres.org\/en\/wp-json\/wp\/v2\/media\/2778"}],"wp:attachment":[{"href":"http:\/\/metzineres.org\/en\/wp-json\/wp\/v2\/media?parent=2780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/metzineres.org\/en\/wp-json\/wp\/v2\/categories?post=2780"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/metzineres.org\/en\/wp-json\/wp\/v2\/tags?post=2780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}