{"id":2766,"date":"2023-11-24T02:08:01","date_gmt":"2023-11-24T02:08:01","guid":{"rendered":"https:\/\/metzineres.org\/?p=2766"},"modified":"2025-01-17T02:08:48","modified_gmt":"2025-01-17T02:08:48","slug":"16-dias-de-accion-para-eliminar-la-violencia-contra-las-mujerxs-que-usan-drogas-campana-evawud2023","status":"publish","type":"post","link":"http:\/\/metzineres.org\/es\/16-dias-de-accion-para-eliminar-la-violencia-contra-las-mujerxs-que-usan-drogas-campana-evawud2023\/","title":{"rendered":"16 d\u00edas de acci\u00f3n para eliminar la violencia contra las mujerxs que usan drogas &#8211; Campa\u00f1a #EVAWUD2023"},"content":{"rendered":"<p>Con motivo de la\u00a0<strong>Campa\u00f1a Internacional para la Eliminaci\u00f3n de la Violencia contra las Mujeres 2023<\/strong>, la Red Internacional de Mujeres y Reducci\u00f3n de Da\u00f1os (<strong>WHRIN<\/strong>) y Metzineres en colaboraci\u00f3n con otras organizaciones como\u00a0<strong>YouthRISE, EuroNPUD y EWNA<\/strong>,\u00a0pedimos que se ponga fin\u00a0a todas las formas de violencia contra las mujerxs y personas de g\u00e9nero diverso que usan drogas,\u00a0as\u00ed como mejorar las pol\u00edticas de drogas desde una perspectiva feminista, de derechos humanos y reducci\u00f3n de da\u00f1os.<\/p>\n<p>Las mujerxs y personas de g\u00e9nero diverso que usan drogas est\u00e1n sujetas a una\u00a0<strong>amplia gama de violencias<\/strong>, muchas a niveles extremos, debido a las normas patriarcales combinadas con la prohibici\u00f3n punitiva de algunas drogas. El estigma impulsado por el Estado, la criminalizaci\u00f3n, las normas de g\u00e9nero perjudiciales y la corrupci\u00f3n generan da\u00f1os sustanciales en la salud y seguridad. Estos factores act\u00faan como barreras entre ellxs y\u00a0los servicios de reducci\u00f3n de da\u00f1os y de atenci\u00f3n a la violencia de g\u00e9nero.<\/p>\n<p>Las mujerxs y personas de g\u00e9nero diverso que usan drogas experimentan\u00a0<strong>violencia machista hasta 25 veces m\u00e1s que el resto<\/strong>. Esta violencia incluye, entre otras, asesinatos extrajudiciales, pena de muerte, esterilizaci\u00f3n y abortos forzados y coercitivos, violaci\u00f3n, acoso sexual, p\u00e9rdida de la custodia infantil, encarcelamiento por posesi\u00f3n o uso personal de drogas y penalizaci\u00f3n por uso de drogas durante el embarazo, junto con otros tipos de violaciones, estigma y discriminaciones de g\u00e9nero.<\/p>\n<p>Mujerxs y personas de g\u00e9nero diverso que usan drogas en todo el mundo\u00a0se enfrentan a detenciones arbitrarias, extorsi\u00f3n, violencia policial, tortura y maltrato; m\u00e1s de un tercio de las mujerxs que est\u00e1n en prisi\u00f3n es por delitos relacionados con drogas y el encarcelamiento de mujerxs por delitos de drogas ha aumentado un 53% a nivel mundial desde el a\u00f1o 2000.<\/p>\n<p>Debido a la llamada\u00a0<strong>\u00abguerra contra las drogas\u00bb<\/strong>, lxs supervivientes\u00a0tienen pocos recursos y a menudo no cuentan con apoyo, especialmente en casos de violencia por parte de la polic\u00eda, guardias de prisiones y personal de centros de \u00abtratamiento\u00bb obligatorio. Las experiencias de violencia contra las mujerxs que usan drogas son a\u00fan m\u00e1s extremas para aquellas que enfrentan\u00a0<strong>opresiones interseccionales<\/strong>, como las mujerxs racializadas, trabajadoras sexuales o mujeres trans. Adem\u00e1s, lxs j\u00f3venes enfrentan m\u00e1s barreras para acceder a servicios esenciales de salud y reducci\u00f3n de da\u00f1os debido a pol\u00edticas y leyes sobre restricciones de edad.<\/p>\n<p>WHRIN, Metzineres y el resto de entidades se\u00f1alamos, ya que trabajamos junto a mujerxs y personas de g\u00e9nero diverso que usan drogas y documentamos acciones y servicios\u00a0liderados entre iguales, que\u00a0<strong>las respuestas apropiadas a estas desigualdades y violaciones son claras:<\/strong><\/p>\n<ul>\n<li>La\u00a0<strong>participaci\u00f3n<\/strong>\u00a0significativa\u00a0<strong>de la comunidad<\/strong>\u00a0debe ser la piedra angular de todas las respuestas de buenas pr\u00e1cticas en el desarrollo de servicios de violencia de g\u00e9nero, ya que la criminalizaci\u00f3n del uso de drogas se erige como una barrera principal entre las mujerxs y personas de g\u00e9nero diverso que usan drogas y la consecuci\u00f3n de los derechos humanos, incluido el derecho a la seguridad, el acceso a la reducci\u00f3n de da\u00f1os y otros servicios\u00a0sanitarios esenciales.<\/li>\n<li>Tambi\u00e9n es imperativa una\u00a0<strong>descriminalizaci\u00f3n<\/strong>\u00a0que elimine todas las sanciones y castigos, incluidos los programas de tratamiento impuestos por coacci\u00f3n o un tribunal, para todas las personas que usan drogas y para todo tipo de drogas. Una descriminalizaci\u00f3n adecuadamente implementada reducir\u00eda el estigma y la violencia asociadas a la \u00abguerra contra las drogas\u00bb.<\/li>\n<li>La expansi\u00f3n de la\u00a0<strong>reducci\u00f3n de da\u00f1os<\/strong>\u00a0y la inclusi\u00f3n de la prevenci\u00f3n y mitigaci\u00f3n de la violencia tambi\u00e9n son fundamentales, as\u00ed como tambi\u00e9n los servicios de apoyo\u00a0con perspectiva de\u00a0g\u00e9nero y apropiados para cada edad.<\/li>\n<li>Tambi\u00e9n es importante se\u00f1alar que la<strong>\u00a0salud sexual y reproductiva<\/strong>\u00a0se promueve actualmente como un servicio esencial adicional que debe incorporarse dentro del conjunto de servicios de reducci\u00f3n de da\u00f1os para personas que usan drogas, y que la prestaci\u00f3n de servicios con buenas pr\u00e1cticas integra servicios especializados en la atenci\u00f3n a las violencias.<\/li>\n<\/ul>\n<p>Metzineres\u00a0y WHRIN, EuroNPUD, YouthRISE y ENWA hacemos un llamado para poner fin a la \u00abguerra contra las drogas\u00bb y a la violencia contra las mujerxs y personas de g\u00e9nero diverso que usan drogas. La legislaci\u00f3n y los principios legales, procedimientos, pol\u00edticas, programas y pr\u00e1cticas relacionadas con la justicia penal deben ser revisados para determinar si son adecuados para prevenir y eliminar esta violencia. Si se encuentra que tienen un impacto negativo, deben modificarse para garantizar que las personas que usan drogas disfruten de un trato justo e igualitario.<\/p>\n<p><strong>Un\u00edos a nosotrxs<\/strong>\u00a0para garantizar que los recursos y los marcos legislativos respalden la seguridad y los derechos humanos de las mujerxs y personas de g\u00e9nero diverso que usan drogas!<\/p>\n<h3><strong><a class=\"postlink\" href=\"https:\/\/metzineres.net\/imgdata\/programa_EVAWUD_2023.pdf\" target=\"_blank\" rel=\"noopener\">DESCARGA EL PROGRAMA DE METZINERES #16D\u00cdAS #EVAWUD2023<\/a><\/strong><\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/metzineres.net\/imgdata\/poster_evawud2023_instagram_castella.png\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo de la\u00a0Campa\u00f1a Internacional para la Eliminaci\u00f3n de la Violencia contra las Mujeres 2023, la Red Internacional de Mujeres y Reducci\u00f3n de Da\u00f1os (WHRIN) y Metzineres en colaboraci\u00f3n con otras organizaciones como\u00a0YouthRISE, EuroNPUD y EWNA,\u00a0pedimos que se ponga fin\u00a0a todas las formas de violencia contra las mujerxs y personas de g\u00e9nero diverso que usan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[],"class_list":["post-2766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones"],"_links":{"self":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/2766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/comments?post=2766"}],"version-history":[{"count":1,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/2766\/revisions"}],"predecessor-version":[{"id":2770,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/2766\/revisions\/2770"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media\/2767"}],"wp:attachment":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media?parent=2766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/categories?post=2766"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/tags?post=2766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}