{"id":2811,"date":"2023-10-24T02:19:27","date_gmt":"2023-10-24T02:19:27","guid":{"rendered":"https:\/\/metzineres.org\/?p=2811"},"modified":"2026-04-17T07:58:06","modified_gmt":"2026-04-17T07:58:06","slug":"cannabis-como-herramienta-de-reduccion-de-danos-2a-edicio","status":"publish","type":"post","link":"http:\/\/metzineres.org\/es\/cannabis-como-herramienta-de-reduccion-de-danos-2a-edicio\/","title":{"rendered":"Cannabis como herramienta de reducci\u00f3n de da\u00f1os (2\u00aa edici\u00f3)"},"content":{"rendered":"<p>Ya est\u00e1 aqu\u00ed!!! Por fin podemos sacar a la luz la\u00a0<strong>segunda edici\u00f3n\u00a0<\/strong>de\u00a0<strong>\u2018Cannabis como herramienta de reducci\u00f3n de da\u00f1os\u2019<\/strong>, un material elaborado a partir de las experiencias de las participantes de Metzineres en colaboraci\u00f3n con personas expertas en drogas y g\u00e9nero. Con imagen renovada y una revisi\u00f3n del texto original!<\/p>\n<p>Recordamos que esta herramienta est\u00e1 basada en la perspectiva de la<strong>\u00a0\u2018reducci\u00f3n de da\u00f1os de espectro completo\u2019<\/strong>: es decir, en aquellas pol\u00edticas y estrategias orientadas a minimizar los consecuencias perjudiciales que puede tener el uso de algunas sustancias (as\u00ed como los impactos negativos de los pol\u00edticas prohibicionistas sobre las drogas), atendiendo a la diversidad de contextos y factores estructurales que interact\u00faan con este uso.<\/p>\n<p>En este caso, hablamos del cannabis: una sustancia que ha sido utilizada como tratamiento de m\u00faltiples enfermedades y malestares a lo largo del tiempo en numerosas culturas.<\/p>\n<p>Muchas de lxs participantes de\u00a0Metzineres\u00a0<strong>usamos esta planta por diferentes motivos<\/strong>: para encontrar placer; para aligerar malestares f\u00edsicos; para soportar diferentes situaciones de vulnerabilidad, estigma y violencia&#8230; Pero tambi\u00e9n para reducir el dolor; modular el efecto de otras sustancias psicoactivas con m\u00e1s\u00a0riesgos asociados; trastornos alimentarios; soportar efectos de la quimioterapia o la menopausia; alteraciones del sue\u00f1o; ansiedad; angustia; o para combatir\u00a0el estr\u00e9s derivado del miedo y el trauma, entre otros.<\/p>\n<p>Este material est\u00e1 pensado para ser compartido entre iguales, con el objetivo de generar una reflexi\u00f3n comunitaria en el \u00e1mbito de los pol\u00edticas de drogas sobre una realidad muy poco observada hasta ahora. En este sentido, invitamos tanto a personas individuales como a entidades a descargarlo y a difundirlo entre\u00a0sus redes de contactes.<\/p>\n<p><strong>Disponible en catal\u00e1n, castellano e ingl\u00e9s!<\/strong><br \/>\nIdea y textos: Metzineres<br \/>\nCon el apoyo de: RDRCannabis, Fundaci\u00f3 ICEERS i REMA<br \/>\nIlustraciones:\u00a0Andre\u00a0Gaetano<\/p>\n<p>En caso de desear el material en formato de impresi\u00f3n en acorde\u00f3n, pod\u00e9is escribir un email a:\u00a0<strong>comunicacio@metzineres.org<\/strong><\/p>\n<p><strong>DESCARGA:<\/strong><\/p>\n<h2><strong><a href=\"https:\/\/metzineres.org\/wp-content\/uploads\/2023\/10\/CAT-NUEVO-MATERIAL-CANNABIS.pdf\">[CAT] C\u00e0nnabis com a eina de reducci\u00f3 de danys<\/a><\/strong><\/h2>\n<h2><strong><a href=\"https:\/\/metzineres.org\/wp-content\/uploads\/2023\/10\/CAST-NUEVO-MATERIAL-CANNABIS.pdf\">[CAS] Cannabis como herramienta de reducci\u00f3n de da\u00f1os<\/a><\/strong><strong><br \/>\n<\/strong><\/h2>\n<h2><strong><a href=\"https:\/\/metzineres.org\/wp-content\/uploads\/2023\/10\/ENG-NUEVO-MATERIAL-CANNABIS_compressed.pdf\">[ENG] Cannabis as a harm reduction tool<\/a><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1 aqu\u00ed!!! Por fin podemos sacar a la luz la\u00a0segunda edici\u00f3n\u00a0de\u00a0\u2018Cannabis como herramienta de reducci\u00f3n de da\u00f1os\u2019, un material elaborado a partir de las experiencias de las participantes de Metzineres en colaboraci\u00f3n con personas expertas en drogas y g\u00e9nero. Con imagen renovada y una revisi\u00f3n del texto original! Recordamos que esta herramienta est\u00e1 basada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[],"class_list":["post-2811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones"],"_links":{"self":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/2811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/comments?post=2811"}],"version-history":[{"count":6,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/2811\/revisions"}],"predecessor-version":[{"id":5339,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/2811\/revisions\/5339"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media\/2812"}],"wp:attachment":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media?parent=2811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/categories?post=2811"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/tags?post=2811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}