{"id":3119,"date":"2022-11-18T03:27:18","date_gmt":"2022-11-18T03:27:18","guid":{"rendered":"https:\/\/metzineres.org\/?p=3119"},"modified":"2025-04-07T15:36:54","modified_gmt":"2025-04-07T15:36:54","slug":"pasado-presente-y-futuro-del-regimen-internacional-de-control-de-drogas","status":"publish","type":"post","link":"http:\/\/metzineres.org\/es\/pasado-presente-y-futuro-del-regimen-internacional-de-control-de-drogas\/","title":{"rendered":"Pasado, presente y futuro del r\u00e9gimen internacional de control de drogas"},"content":{"rendered":"<p>No te pierdas el webinar \u2018Pasado, presente y futuro del r\u00e9gimen internacional de control de drogas\u2019, un curso en el que se analizar\u00e1 el papel que desempe\u00f1a la sociedad civil en las pol\u00edticas internacionales de drogas.<\/p>\n<p>Adem\u00e1s, se evaluar\u00e1n los logros conseguidos en esta materia durante los \u00faltimos a\u00f1os, as\u00ed como el alcance de la participaci\u00f3n de las entidades sociales en la toma de decisiones y en las estrategias llevadas a cabo.<\/p>\n<p>El encuentro online, que se desarrollar\u00e1 en dos sesiones, los d\u00edas 23 y 29 de noviembre en horario de 16:00 a 17:00 horas, est\u00e1 impulsado por la Comisi\u00f3n de Pol\u00edticas Globales de UNAD con el apoyo de IDPC. En estas dos jornadas, representantes institucionales y de entidades como ICEERS, Instituto R\u00eda, IDPC, LANPUD y Metzineres, compartir\u00e1n conocimientos y opiniones sobre una realidad que marca el trabajo diario con las personas usuarias.<\/p>\n<p>Para seguir las sesiones es necesario inscribirse\u00a0en este enlace.<\/p>\n<h3><a class=\"postlink\" href=\"https:\/\/metzineres.net\/imgdata\/1668158108_programa_curso_online_regimen_control_de_drogas_ok.pdf\" target=\"_blank\" rel=\"noopener\">DESCARGA EL PROGRAMA AQU\u00cd<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>No te pierdas el webinar \u2018Pasado, presente y futuro del r\u00e9gimen internacional de control de drogas\u2019, un curso en el que se analizar\u00e1 el papel que desempe\u00f1a la sociedad civil en las pol\u00edticas internacionales de drogas. Adem\u00e1s, se evaluar\u00e1n los logros conseguidos en esta materia durante los \u00faltimos a\u00f1os, as\u00ed como el alcance de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[],"class_list":["post-3119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones"],"_links":{"self":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/comments?post=3119"}],"version-history":[{"count":2,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3119\/revisions"}],"predecessor-version":[{"id":4456,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3119\/revisions\/4456"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media\/3120"}],"wp:attachment":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media?parent=3119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/categories?post=3119"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/tags?post=3119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}