{"id":3128,"date":"2022-11-02T03:28:27","date_gmt":"2022-11-02T03:28:27","guid":{"rendered":"https:\/\/metzineres.org\/?p=3128"},"modified":"2025-01-17T03:29:02","modified_gmt":"2025-01-17T03:29:02","slug":"metziagenda-de-noviembre-2022","status":"publish","type":"post","link":"http:\/\/metzineres.org\/es\/metziagenda-de-noviembre-2022\/","title":{"rendered":"MetziAgenda de Noviembre 2022"},"content":{"rendered":"<p>Calendario de actividades semanales para lxs participantes de Metzineres. Este mes tenemos:<\/p>\n<ul>\n<li>Costura guerrillera<\/li>\n<li>Taller de Fanzine<\/li>\n<li>Reuniones de la XADUD (Red de Mujerxs que Usan Drogas), en el \u00c1gora Juan Andr\u00e9s Ben\u00edtez<\/li>\n<li>Kosmetik\u00edn: Taller de cosm\u00e9tica natural<\/li>\n<li>Autodefensa feminista<\/li>\n<li>Asamblea<\/li>\n<li>Reuniones DIRD (Mujerxs Impulsoras de Reducci\u00f3n de Da\u00f1os)<\/li>\n<li>Prente&#8217;l Pel: Peluquer\u00eda\u00a0con Nani<\/li>\n<li>Monologueando: Taller de mon\u00f3logos, con Vidda Priego<\/li>\n<li>Pa&#8217;Ella: La paella de los viernes en el \u00c1gora Juan Andr\u00e9s Ben\u00edtez<\/li>\n<li>MetziRadio en el \u00c1gora Juan Andr\u00e9s Ben\u00edtez (quincenal)<\/li>\n<li>Cabaret (quincenal)<\/li>\n<li>Crispelis: Pelis y palomitas!<\/li>\n<\/ul>\n<p>Actividades especiales de noviembre:<\/p>\n<ul>\n<li>Domingo 6: Flea Market<\/li>\n<li>Domingo 20: D\u00eda Internacional de la Memoria Trans<\/li>\n<li>Mi\u00e9rcoles 23: D\u00eda Internacional de las Personas Sin Hogar<\/li>\n<li>Viernes 25: D\u00eda Internacional de Eliminaci\u00f3n de la Violencia Hacia las Mujerxs, y\u00a0comienzo de la campa\u00f1a #16Days<\/li>\n<\/ul>\n<p>Adem\u00e1s, siempre disponible:<\/p>\n<ul>\n<li>MetziSpa<\/li>\n<li>Taller de Naloxona express<\/li>\n<li>Acompa\u00f1amiento sanitario, social y educativo<\/li>\n<li>Dormir de d\u00eda<\/li>\n<li>Ropero, ducha y lavadora<\/li>\n<li>Ordenadores e Internet<\/li>\n<li>ArtiSana: Espacio de Arteterapia<\/li>\n<\/ul>\n<p>Horario:<\/p>\n<ul>\n<li>Lunes, mi\u00e9rcoles, jueves, viernes* y s\u00e1bado de 14 a 21h.<\/li>\n<li>Martes de 16 a 21h.<\/li>\n<li>Domingo cerrado.<\/li>\n<\/ul>\n<p>*Los viernes estamos en el \u00e1gora Juan Andr\u00e9s Ben\u00edtez con nuestra Pa&#8217;Ella, desde el mediod\u00eda hasta las 17h, aprox. Luego vamos al local.<\/p>\n<p>Direcci\u00f3n del local de Metzineres:<br \/>\nCarrer de la Lluna, 3<br \/>\nBarrio del\u00a0Raval (Barcelona)<\/p>\n<p>Direcci\u00f3n del \u00c1gora Juan Andr\u00e9s Ben\u00edtez<br \/>\nCarrer de l&#8217;Aurora, 13<br \/>\nBarri del Raval (Barcelona)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Calendario de actividades semanales para lxs participantes de Metzineres. Este mes tenemos: Costura guerrillera Taller de Fanzine Reuniones de la XADUD (Red de Mujerxs que Usan Drogas), en el \u00c1gora Juan Andr\u00e9s Ben\u00edtez Kosmetik\u00edn: Taller de cosm\u00e9tica natural Autodefensa feminista Asamblea Reuniones DIRD (Mujerxs Impulsoras de Reducci\u00f3n de Da\u00f1os) Prente&#8217;l Pel: Peluquer\u00eda\u00a0con Nani Monologueando: Taller [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[],"class_list":["post-3128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones"],"_links":{"self":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/comments?post=3128"}],"version-history":[{"count":1,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3128\/revisions"}],"predecessor-version":[{"id":3132,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3128\/revisions\/3132"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media\/3129"}],"wp:attachment":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media?parent=3128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/categories?post=3128"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/tags?post=3128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}