{"id":3227,"date":"2022-07-07T03:45:43","date_gmt":"2022-07-07T03:45:43","guid":{"rendered":"https:\/\/metzineres.org\/?p=3227"},"modified":"2025-01-17T03:46:08","modified_gmt":"2025-01-17T03:46:08","slug":"lazona-mercat-spot-botiga-online-de-metzineres","status":"publish","type":"post","link":"http:\/\/metzineres.org\/es\/lazona-mercat-spot-botiga-online-de-metzineres\/","title":{"rendered":"LaZona Mercat | Spot botiga online de Metzineres"},"content":{"rendered":"<p>\u00bfConoc\u00e9is nuestra tienda en l\u00ednea de LaZona Mercat? Desde hace unos meses, todos nuestros productos est\u00e1n disponibles en este mercado digital de productos y servicios de consumo responsable. Porque a Metzineres tambi\u00e9n apostamos por un modelo de consumo local, centrado en las personas y en equilibrio con el medio ambiente.<\/p>\n<p>Los productos que encontrar\u00e1s en nuestra tienda, a la que puedes acceder a trav\u00e9s de nuestra web o directamente a lazona.coop, son camisetas y bolsos del g\u00e9nero Continental Clothing, empresa textil l\u00edder en innovaci\u00f3n, dise\u00f1o y sostenibilidad, y con estampaci\u00f3n de Top manta, la marca social y solidaria del colectivo mantero de Barcelona.<\/p>\n<p>Y\u00a0es que a LaZona todos los productos son de proximidad, respetuosos con los derechos de las trabajadoras que participan en su elaboraci\u00f3n y sostenibles. Y tambi\u00e9n podr\u00e1s contratar servicios regidos por los mismos valores!<\/p>\n<p>Cuando tengas que comprar algo en l\u00ednea, recuerda LaZona Mercat y haz que tus compras en Internet tambi\u00e9n sean de consumo responsable!<\/p>\n<p>Os dejamos con el video que nos han hecho para promocionar nuestros productos:<\/p>\n<p><iframe class=\"frameencastat videoencastat\" title=\"\" src=\"https:\/\/www.youtube.com\/embed\/tcY548nAI_M\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfConoc\u00e9is nuestra tienda en l\u00ednea de LaZona Mercat? Desde hace unos meses, todos nuestros productos est\u00e1n disponibles en este mercado digital de productos y servicios de consumo responsable. Porque a Metzineres tambi\u00e9n apostamos por un modelo de consumo local, centrado en las personas y en equilibrio con el medio ambiente. Los productos que encontrar\u00e1s en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[],"class_list":["post-3227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones"],"_links":{"self":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/comments?post=3227"}],"version-history":[{"count":1,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3227\/revisions"}],"predecessor-version":[{"id":3231,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3227\/revisions\/3231"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media\/3228"}],"wp:attachment":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media?parent=3227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/categories?post=3227"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/tags?post=3227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}