{"id":3245,"date":"2022-06-20T03:48:46","date_gmt":"2022-06-20T03:48:46","guid":{"rendered":"https:\/\/metzineres.org\/?p=3245"},"modified":"2026-04-08T09:36:29","modified_gmt":"2026-04-08T09:36:29","slug":"nuevo-material-cannabis-como-herramienta-de-reduccion-de-danos","status":"publish","type":"post","link":"http:\/\/metzineres.org\/es\/nuevo-material-cannabis-como-herramienta-de-reduccion-de-danos\/","title":{"rendered":"Nuevo material: Cannabis como herramienta de reducci\u00f3n de da\u00f1os"},"content":{"rendered":"<p>El uso de cannabis como tratamiento de m\u00faltiples enfermedades y malestares ha sido documentado a lo largo de los tiempos en numerosas culturas.<\/p>\n<p>Muchas de las participantes de Metzineres, usamos esta planta por diferentes motivos. Algunos de ellos tienen que ver con el placer, otros con el alivio de malestares f\u00edsicos, con poder sobrellevar de la mejor manera las diferentes situaciones de vulnerabilidad, estigma y violencia que sobrevivimos. Utilizamos cannabis para reducir el dolor, para modular el efecto otras sustancias psicoactivas con m\u00e1s riesgos asociados, en los trastornos alimenticios, para sobrellevar los efectos secundarios de la quimioterapia, en las alteraciones del sue\u00f1o, la ansiedad, la angustia y, para paliar el estr\u00e9s derivado del miedo y el trauma, entre otros.<\/p>\n<p>El material \u00abCannabis como herramienta de reducci\u00f3n de da\u00f1os\u00bb ha sido elaborado a partir de las experiencias de las participantes de Metzineres y en colaboraci\u00f3n con otras personas expertas en drogas y g\u00e9nero.<\/p>\n<p>Se trata de una herramienta basada en la filosof\u00eda del espectro completo de la reducci\u00f3n de da\u00f1os, ideada para ser compartida entre iguales y con el fin de generar una reflexi\u00f3n comunitaria en el \u00e1mbito de las pol\u00edticas de drogas sobre una realidad muy poco observada hasta ahora.<br \/>\nPara favorecer su alcance, el material est\u00e1 elaborado en catal\u00e1n, castellano e ingl\u00e9s. Invitamos a que tanto personas individuales como entidades lo descarguen y compartan en sus redes de contactos.<\/p>\n<p>Idea y textos: Metzineres<br \/>\nCon la financiaci\u00f3n de: Fundaci\u00f3n Alchimia Solidaria<br \/>\nCon el apoyo de: RDRCannabis, Fundaci\u00f3n ICEERS y REMA<br \/>\nIlustraciones: Maligneando<\/p>\n<p>DESCARGA:<\/p>\n<p>Castellano:\u00a0<a class=\"postlink\" href=\"https:\/\/metzineres.net\/imgdata\/Cannabis_como_herramienta_de_reducci__n_de_da__os_Metzineres2022.pdf\" target=\"_blank\" rel=\"noopener\">Cannabis como herramienta de reducci\u00f3n de da\u00f1os<\/a><\/p>\n<p>Catal\u00e0:\u00a0<a class=\"postlink\" href=\"https:\/\/metzineres.net\/imgdata\/Cannabis_com_a_eina_de_reducci___de_danys_Metzineres_2022.pdf\" target=\"_blank\" rel=\"noopener\">Cannabis com a eina de reducci\u00f3 de danys<\/a><\/p>\n<p>English:\u00a0<a class=\"postlink\" href=\"https:\/\/metzineres.net\/imgdata\/Cannabis_as_a_harm_reduction_tool_by_Metzineres_2022.pdf\" target=\"_blank\" rel=\"noopener\">Cannabis as a harm reduction tool<\/a><\/p>\n<p>En caso de desear el material el formato de impresi\u00f3n en modo acorde\u00f3n, escribir un email a: comunicacio@metzineres.org<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El uso de cannabis como tratamiento de m\u00faltiples enfermedades y malestares ha sido documentado a lo largo de los tiempos en numerosas culturas. Muchas de las participantes de Metzineres, usamos esta planta por diferentes motivos. Algunos de ellos tienen que ver con el placer, otros con el alivio de malestares f\u00edsicos, con poder sobrellevar de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[],"class_list":["post-3245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones"],"_links":{"self":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/comments?post=3245"}],"version-history":[{"count":3,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3245\/revisions"}],"predecessor-version":[{"id":5208,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3245\/revisions\/5208"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media\/3246"}],"wp:attachment":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media?parent=3245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/categories?post=3245"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/tags?post=3245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}