{"id":3335,"date":"2020-09-01T04:08:21","date_gmt":"2020-09-01T04:08:21","guid":{"rendered":"https:\/\/metzineres.org\/?p=3335"},"modified":"2025-01-17T04:08:49","modified_gmt":"2025-01-17T04:08:49","slug":"no-mas-muertes-por-sobredosis-2020","status":"publish","type":"post","link":"http:\/\/metzineres.org\/es\/no-mas-muertes-por-sobredosis-2020\/","title":{"rendered":"No m\u00e1s muertes por sobredosis 2020"},"content":{"rendered":"<p>El 31 de Agosto de 2020, como cada a\u00f1o, celebramos en el \u00c1gora Juan Andr\u00e9s Ben\u00edtez el D\u00eda de la Sensibilizaci\u00f3n sobre las Muertes por Sobredosis. Fue un placer compartir espacio y experiencias con la XADUD y Familias de Presos de Catalunya.<\/p>\n<p>Son muchxs lxs compa\u00f1erxs que han ca\u00eddo en esta dura guerra contra las drogas, que no es m\u00e1s que una guerra contra las personas que usan drogas.<br \/>\nLas instituciones p\u00fablicas deben dejar de mirar hacia otro lado para hacer frente a esta problem\u00e1tica derivada de la propia prohibici\u00f3n.<br \/>\nEs urgente una mirada innovadora y atrevida con intervenciones de base comunitaria ancladas en derechos humanos y feminismo interseccional.<\/p>\n<p>Administraciones, organizaciones y sociedad deben ir de la mano para un mismo prop\u00f3sito: \u00a1NO M\u00c1S V\u00cdCTIMAS DE LA GUERRA CONTRA LAS DROGAS! \u270a<\/p>\n<p>V\u00eddeo: Carmen Molina<\/p>\n<p><iframe class=\"frameencastat videoencastat\" title=\"\" src=\"https:\/\/www.youtube.com\/embed\/VJd4_NTYumY\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 31 de Agosto de 2020, como cada a\u00f1o, celebramos en el \u00c1gora Juan Andr\u00e9s Ben\u00edtez el D\u00eda de la Sensibilizaci\u00f3n sobre las Muertes por Sobredosis. Fue un placer compartir espacio y experiencias con la XADUD y Familias de Presos de Catalunya. Son muchxs lxs compa\u00f1erxs que han ca\u00eddo en esta dura guerra contra las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[],"class_list":["post-3335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones"],"_links":{"self":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/comments?post=3335"}],"version-history":[{"count":1,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3335\/revisions"}],"predecessor-version":[{"id":3339,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/3335\/revisions\/3339"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media\/3336"}],"wp:attachment":[{"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media?parent=3335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/categories?post=3335"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/tags?post=3335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}