{"id":2164,"date":"2024-07-04T04:41:47","date_gmt":"2024-07-04T04:41:47","guid":{"rendered":"https:\/\/metzineres.org\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/"},"modified":"2024-12-30T23:43:02","modified_gmt":"2024-12-30T23:43:02","slug":"milers_de_veus_cridant_suport_no_castig_van_sacsej","status":"publish","type":"post","link":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/","title":{"rendered":"Milers de veus cridant \u00abSuport. No c\u00e0stig\u00bb van sacsejar la Rambla del Raval"},"content":{"rendered":"<h6>Per Sophia Vargas<\/h6>\n<p>El dimecres 26 de juny les Metzineres vam cridar\u00a0<strong>\u201cSuport. No c\u00e0stig\u201d<\/strong>, en el marc del Dia d&#8217;Acci\u00f3 Global \u201cSupport Don&#8217;t Punish\u201d. Aix\u00ed \u00e9s com la Rambla del Raval es va convertir en un vibrant escenari de resist\u00e8ncia i solidaritat on les persones usu\u00e0ries de drogues\u00a0<strong>vam advocar per pol\u00edtiques m\u00e9s humanes, enfocades en la salut p\u00fablica i en els drets humans en lloc de la criminalitzaci\u00f3 i el c\u00e0stig.<\/strong><\/p>\n<p>Des de bon mat\u00ed, les Metzineres, juntament amb la Xarxa Catalana de Persones que Usen Drogues (CATNPUD), la Xarxa de Feministes Antiprohibicionistes en l&#8217;\u00c0mbit de les Drogues (REMA), la Fundaci\u00f3 \u00c0mbit Prevenci\u00f3, ABD i la Xarxa de Dones que Usen Drogues (XADUD), ens vam reunir per fer visible el nostre missatge:\u00a0<strong>la prohibici\u00f3 nom\u00e9s serveix per castigar, estigmatitzar i penalitzar aquelles que som usu\u00e0ries de drogues, perpetuant diverses formes de viol\u00e8ncia sobre els nostres cossos i les nostres vides,<\/strong>\u00a0afavorint l&#8217;exclusi\u00f3 que ens deixa al marge de la societat i sense els nostres drets.<\/p>\n<p>Les activitats van comen\u00e7ar amb una c\u00e0lida acollida per part dels ve\u00efns del barri del Raval, que es van sumar a les diverses accions, com la gimcana que va consistir en activitats l\u00fadiques sobre temes crucials com\u00a0<strong>l&#8217;antiprohibicionisme, la viol\u00e8ncia institucional, el treball sexual, el consum de drogues i la situaci\u00f3 de les persones sense llar.<\/strong><\/p>\n<p>Una de les activitats m\u00e9s destacades va ser la pintura d&#8217;un mural col\u00b7lectiu, on es van plasmar missatges i s\u00edmbols de resist\u00e8ncia i suport a les persones que usen drogues i viuen amb VIH\/SIDA. Es va replicar col\u00b7lectivament el fam\u00f3s mural ubicat al Museu d&#8217;Art Contemporani de Barcelona (MACBA): \u00abTots junts podem parar la SIDA\u00bb de l&#8217;artista Keith Haring. Aquesta obra d&#8217;art ic\u00f2nica transmet un\u00a0<strong>poder\u00f3s missatge d&#8217;unitat i acci\u00f3 col\u00b7lectiva, simbolitzant la capacitat d&#8217;unir-nos i enfrontar junts els desafiaments.<\/strong><\/p>\n<p>Mentrestant, una transmissi\u00f3 en viu de r\u00e0dio ens va oferir l&#8217;oportunitat d&#8217;aprendre sobre la hist\u00f2ria del prohibicionisme a Barcelona. Tamb\u00e9 es va parlar sobre el controvertit Pla Endre\u00e7a, promogut per l&#8217;administraci\u00f3 p\u00fablica de la ciutat, i l&#8217;impacte negatiu que t\u00e9 per a les persones sense llar i consumidores de drogues.<strong>\u00a0Ja que les seves mesures ens exposen a m\u00e9s situacions de vulnerabilitat i viol\u00e8ncia.<\/strong><\/p>\n<p>La r\u00e0dio tamb\u00e9 va servir de plataforma perqu\u00e8 les veus d&#8217;aquelles que hem estat marginades se sentissin ben fort i clar. Una humorista trans, queer i bisexual va presentar l&#8217;esdeveniment, omplint l&#8217;ambient de rialles i refor\u00e7ant l&#8217;esperit d&#8217;inclusi\u00f3.<\/p>\n<p>El fet que aquest esdeveniment es realitz\u00e9s en un espai p\u00fablic va tenir un significat profund, perqu\u00e8 les persones que habitualment estem als marges de la societat vam ocupar la Rambla del Raval,\u00a0<strong>visibilitzant que mereixem i podem ocupar aquests espais, gaudint i expressant-nos lliurement sense estigmes, teixint lla\u00e7os amb la comunitat.<\/strong>\u00a0La resposta del barri va ser molt positiva.<\/p>\n<p>La jornada va concloure amb la convicci\u00f3 que juntes podem aconseguir un canvi real i significatiu per\u00a0<strong>posar fi a la criminalitzaci\u00f3, estigmatitzaci\u00f3 i a les pol\u00edtiques i pr\u00e0ctiques violentes contra les nostres comunitats.<\/strong>\u00a0Aix\u00ed com garantir reparaci\u00f3 i construir un m\u00f3n on les causes estructurals d&#8217;exclusi\u00f3 siguin eliminades i on totes les persones tinguem dret a una vida plena, digna i lliure de viol\u00e8ncies.<\/p>\n<p>El dia global de \u201cSupport Don&#8217;t Punish\u201d se celebra des de fa m\u00e9s d&#8217;una d\u00e8cada. Des de llavors, ha potenciat una xarxa global i descentralitzada d&#8217;agents de canvi en mat\u00e8ria de pol\u00edtiques de drogues i Reducci\u00f3 de Danys.<\/p>\n<h6>Fotografie: Andre Gaetano, Fotografa Metzineres.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Per Sophia Vargas El dimecres 26 de juny les Metzineres vam cridar\u00a0\u201cSuport. No c\u00e0stig\u201d, en el marc del Dia d&#8217;Acci\u00f3 Global \u201cSupport Don&#8217;t Punish\u201d. Aix\u00ed \u00e9s com la Rambla del Raval es va convertir en un vibrant escenari de resist\u00e8ncia i solidaritat on les persones usu\u00e0ries de drogues\u00a0vam advocar per pol\u00edtiques m\u00e9s humanes, enfocades en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1746,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[57],"tags":[],"class_list":["post-2164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicacions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Milers de veus cridant &quot;Suport. No c\u00e0stig&quot; van sacsejar la Rambla del Raval - Metzineres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milers de veus cridant &quot;Suport. No c\u00e0stig&quot; van sacsejar la Rambla del Raval - Metzineres\" \/>\n<meta property=\"og:description\" content=\"Per Sophia Vargas El dimecres 26 de juny les Metzineres vam cridar\u00a0\u201cSuport. No c\u00e0stig\u201d, en el marc del Dia d&#8217;Acci\u00f3 Global \u201cSupport Don&#8217;t Punish\u201d. Aix\u00ed \u00e9s com la Rambla del Raval es va convertir en un vibrant escenari de resist\u00e8ncia i solidaritat on les persones usu\u00e0ries de drogues\u00a0vam advocar per pol\u00edtiques m\u00e9s humanes, enfocades en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/\" \/>\n<meta property=\"og:site_name\" content=\"Metzineres\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-04T04:41:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-30T23:43:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/person\\\/3eda218c9566f555577231b7402225e4\"},\"headline\":\"Milers de veus cridant \u00abSuport. No c\u00e0stig\u00bb van sacsejar la Rambla del Raval\",\"datePublished\":\"2024-07-04T04:41:47+00:00\",\"dateModified\":\"2024-12-30T23:43:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/\"},\"wordCount\":631,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/B1A9601-scaled.jpg\",\"articleSection\":[\"Publicacions\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/\",\"url\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/\",\"name\":\"Milers de veus cridant \\\"Suport. No c\u00e0stig\\\" van sacsejar la Rambla del Raval - Metzineres\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/B1A9601-scaled.jpg\",\"datePublished\":\"2024-07-04T04:41:47+00:00\",\"dateModified\":\"2024-12-30T23:43:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/B1A9601-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/B1A9601-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/milers_de_veus_cridant_suport_no_castig_van_sacsej\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/metzineres.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Milers de veus cridant \u00abSuport. No c\u00e0stig\u00bb van sacsejar la Rambla del Raval\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/metzineres.org\\\/es\\\/\",\"name\":\"Metzineres\",\"description\":\"Entornos de cobijo para mujeres y personas de g\u00e9nero expansivo que sobreviven a m\u00faltiples violencias.\",\"publisher\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/metzineres.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#organization\",\"name\":\"Metzineres\",\"url\":\"http:\\\/\\\/metzineres.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-metzineres-negro.png\",\"contentUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-metzineres-negro.png\",\"width\":500,\"height\":151,\"caption\":\"Metzineres\"},\"image\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/person\\\/3eda218c9566f555577231b7402225e4\",\"name\":\"admin\",\"sameAs\":[\"https:\\\/\\\/metzineres.org\"],\"url\":\"https:\\\/\\\/metzineres.org\\\/ca\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Milers de veus cridant \"Suport. No c\u00e0stig\" van sacsejar la Rambla del Raval - Metzineres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/","og_locale":"ca_ES","og_type":"article","og_title":"Milers de veus cridant \"Suport. No c\u00e0stig\" van sacsejar la Rambla del Raval - Metzineres","og_description":"Per Sophia Vargas El dimecres 26 de juny les Metzineres vam cridar\u00a0\u201cSuport. No c\u00e0stig\u201d, en el marc del Dia d&#8217;Acci\u00f3 Global \u201cSupport Don&#8217;t Punish\u201d. Aix\u00ed \u00e9s com la Rambla del Raval es va convertir en un vibrant escenari de resist\u00e8ncia i solidaritat on les persones usu\u00e0ries de drogues\u00a0vam advocar per pol\u00edtiques m\u00e9s humanes, enfocades en [&hellip;]","og_url":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/","og_site_name":"Metzineres","article_published_time":"2024-07-04T04:41:47+00:00","article_modified_time":"2024-12-30T23:43:02+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/#article","isPartOf":{"@id":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/"},"author":{"name":"admin","@id":"http:\/\/metzineres.org\/es\/#\/schema\/person\/3eda218c9566f555577231b7402225e4"},"headline":"Milers de veus cridant \u00abSuport. No c\u00e0stig\u00bb van sacsejar la Rambla del Raval","datePublished":"2024-07-04T04:41:47+00:00","dateModified":"2024-12-30T23:43:02+00:00","mainEntityOfPage":{"@id":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/"},"wordCount":631,"commentCount":0,"publisher":{"@id":"http:\/\/metzineres.org\/es\/#organization"},"image":{"@id":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/#primaryimage"},"thumbnailUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg","articleSection":["Publicacions"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/","url":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/","name":"Milers de veus cridant \"Suport. No c\u00e0stig\" van sacsejar la Rambla del Raval - Metzineres","isPartOf":{"@id":"http:\/\/metzineres.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/#primaryimage"},"image":{"@id":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/#primaryimage"},"thumbnailUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg","datePublished":"2024-07-04T04:41:47+00:00","dateModified":"2024-12-30T23:43:02+00:00","breadcrumb":{"@id":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/#primaryimage","url":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg","contentUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/metzineres.org\/ca\/milers_de_veus_cridant_suport_no_castig_van_sacsej\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/metzineres.org\/ca\/"},{"@type":"ListItem","position":2,"name":"Milers de veus cridant \u00abSuport. No c\u00e0stig\u00bb van sacsejar la Rambla del Raval"}]},{"@type":"WebSite","@id":"http:\/\/metzineres.org\/es\/#website","url":"http:\/\/metzineres.org\/es\/","name":"Metzineres","description":"Entornos de cobijo para mujeres y personas de g\u00e9nero expansivo que sobreviven a m\u00faltiples violencias.","publisher":{"@id":"http:\/\/metzineres.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/metzineres.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"http:\/\/metzineres.org\/es\/#organization","name":"Metzineres","url":"http:\/\/metzineres.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"http:\/\/metzineres.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/logo-metzineres-negro.png","contentUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/logo-metzineres-negro.png","width":500,"height":151,"caption":"Metzineres"},"image":{"@id":"http:\/\/metzineres.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/metzineres.org\/es\/#\/schema\/person\/3eda218c9566f555577231b7402225e4","name":"admin","sameAs":["https:\/\/metzineres.org"],"url":"https:\/\/metzineres.org\/ca\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/2164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/comments?post=2164"}],"version-history":[{"count":2,"href":"https:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/2164\/revisions"}],"predecessor-version":[{"id":2170,"href":"https:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/posts\/2164\/revisions\/2170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/media\/1746"}],"wp:attachment":[{"href":"https:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/media?parent=2164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/categories?post=2164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metzineres.org\/ca\/wp-json\/wp\/v2\/tags?post=2164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}