{"id":107,"date":"2024-07-04T04:41:47","date_gmt":"2024-07-04T04:41:47","guid":{"rendered":"https:\/\/metzineres.org\/?p=107"},"modified":"2024-11-08T04:32:35","modified_gmt":"2024-11-08T04:32:35","slug":"miles_de_voces_gritando_apoyo_no_castigo_sacudiero","status":"publish","type":"post","link":"https:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/","title":{"rendered":"Miles de voces gritando \u201cApoyo. No castigo\u201d sacudieron la rambla del Raval"},"content":{"rendered":"<h6>Por Sophia Vargas<\/h6>\n<p>El mi\u00e9rcoles 26 de junio las Metzineres gritamos\u00a0<strong>\u201cApoyo. No castigo\u201d<\/strong>, en el marco del D\u00eda de Acci\u00f3n Global \u201cSupport Don&#8217;t Punish\u201d. Fue as\u00ed como la Rambla del Raval se convirti\u00f3 en un vibrante escenario de resistencia y solidaridad donde personas usuarias de drogas\u00a0<strong>abogamos por pol\u00edticas m\u00e1s humanas, enfocadas en la salud p\u00fablica y en los derechos humanos en lugar de la criminalizaci\u00f3n y el castigo. \u00a0<\/strong><\/p>\n<p>Desde temprano, las Metzineres, junto a la Red Catalana de Personas que Usan Drogas (CATNPUD), la Red de Feministas Antiprohibicionistas en el \u00c1mbito de las Drogas (REMA), la Fundaci\u00f3n \u00c1mbit Prevenci\u00f3, ABD y la Red de Mujeres que Usan Drogas (XADUD), nos reunimos para hacer visible nuestro mensaje:\u00a0<strong>la prohibici\u00f3n no hace m\u00e1s que castigar, estigmatizar y penalizar a quienes somos usuarias de drogas, perpetuando distintas formas de violencia sobre nuestros cuerpos y nuestras vidas,<\/strong>\u00a0favoreciendo la exclusi\u00f3n que nos deja al margen de la sociedad y sin nuestros derechos.<\/p>\n<p>Las actividades comenzaron con una c\u00e1lida acogida por parte de lxs vecinxs del barrio del Raval, quienes se sumaron a las distintas acciones, como la gincana que consisti\u00f3 en actividades l\u00fadicas en temas cruciales como el\u00a0<strong>antiprohibicionismo, la violencia institucional, el trabajo sexual, el consumo de drogas y la situaci\u00f3n de las personas sin hogar.<\/strong><\/p>\n<p>Una de las actividades m\u00e1s destacadas fue la pintura de un mural colectivo, donde se plasmaron mensajes y s\u00edmbolos de resistencia y apoyo a las personas que usan drogas y viven con VIH\/SIDA. Se replic\u00f3 colectivamente el famoso mural ubicado en el Museu d&#8217;Art Contemporani de Barcelona (MACBA): \u00abTodos juntos podemos parar el SIDA\u00bb del artista Keith Haring. Esta obra de arte ic\u00f3nica transmite un\u00a0<strong>poderoso mensaje de unidad y acci\u00f3n colectiva, simbolizando la capacidad de unirnos y enfrentar juntos los desaf\u00edos.<\/strong><\/p>\n<p>Mientras tanto, una transmisi\u00f3n en vivo de radio nos ofreci\u00f3 la oportunidad de escuchar sobre la historia del prohibicionismo en Barcelona. Tambi\u00e9n se convers\u00f3 sobre el controvertido Plan Endre\u00e7a, promovido por la administraci\u00f3n p\u00fablica de la ciudad, y el impacto negativo que tiene para las personas sin techo y consumidoras de drogas.<strong>\u00a0Ya que sus medidas exponen a m\u00e1s situaciones de vulneraci\u00f3n y violencia.<\/strong><\/p>\n<p>La radio tambi\u00e9n sirvi\u00f3 de plataforma para que las voces de quienes hemos sido marginadas se escucharan alto y claro. Una humorista trans, queer y bisexual present\u00f3 el evento, llenando el ambiente de risas y reforzando el esp\u00edritu de inclusi\u00f3n.<\/p>\n<p>El hecho de que este evento se realizara en un espacio p\u00fablico tuvo un significado profundo, porque las personas que habitualmente estamos en los m\u00e1rgenes de la sociedad ocupamos la Rambla del Raval,\u00a0<strong>visibilizando que merecemos y podemos ocupar estos espacios, disfrutando y expres\u00e1ndonos libremente sin estigmas, tejiendo lazos con la comunidad.<\/strong>\u00a0La respuesta del barrio fue muy positiva.<\/p>\n<p>La jornada concluy\u00f3 con la convicci\u00f3n de que juntxs podemos lograr un cambio real y significativo para\u00a0<strong>poner fin a la criminalizaci\u00f3n, estigmatizaci\u00f3n y a las pol\u00edticas y pr\u00e1cticas violentas contra nuestras comunidades.<\/strong>\u00a0Como as\u00ed tambi\u00e9n, garantizar reparaci\u00f3n y construir un mundo donde las causas estructurales de exclusi\u00f3n sean eliminadas y donde todas las personas tengamos derecho a una vida plena, digna y libre de violencias.<\/p>\n<p>El d\u00eda global de \u201cSupport Don&#8217;t Punish\u201d se realiza desde hace m\u00e1s de una d\u00e9cada. Desde entonces, ha potenciado una red global y descentralizada de agentes de cambio en materia de pol\u00edticas de drogas y Reducci\u00f3n de Da\u00f1os.<\/p>\n<h6>\u00a0Fotograf\u00edas: Andre Gaetano, Fotografa Metzineres.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Por Sophia Vargas El mi\u00e9rcoles 26 de junio las Metzineres gritamos\u00a0\u201cApoyo. No castigo\u201d, en el marco del D\u00eda de Acci\u00f3n Global \u201cSupport Don&#8217;t Punish\u201d. Fue as\u00ed como la Rambla del Raval se convirti\u00f3 en un vibrante escenario de resistencia y solidaridad donde personas usuarias de drogas\u00a0abogamos por pol\u00edticas m\u00e1s humanas, enfocadas en la salud p\u00fablica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[],"class_list":["post-107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Miles de voces gritando \u201cApoyo. No castigo\u201d sacudieron la rambla del Raval - Metzineres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miles de voces gritando \u201cApoyo. No castigo\u201d sacudieron la rambla del Raval - Metzineres\" \/>\n<meta property=\"og:description\" content=\"Por Sophia Vargas El mi\u00e9rcoles 26 de junio las Metzineres gritamos\u00a0\u201cApoyo. No castigo\u201d, en el marco del D\u00eda de Acci\u00f3n Global \u201cSupport Don&#8217;t Punish\u201d. Fue as\u00ed como la Rambla del Raval se convirti\u00f3 en un vibrante escenario de resistencia y solidaridad donde personas usuarias de drogas\u00a0abogamos por pol\u00edticas m\u00e1s humanas, enfocadas en la salud p\u00fablica [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/\" \/>\n<meta property=\"og:site_name\" content=\"Metzineres\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-04T04:41:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T04:32:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/person\\\/3eda218c9566f555577231b7402225e4\"},\"headline\":\"Miles de voces gritando \u201cApoyo. No castigo\u201d sacudieron la rambla del Raval\",\"datePublished\":\"2024-07-04T04:41:47+00:00\",\"dateModified\":\"2024-11-08T04:32:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/\"},\"wordCount\":628,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/B1A9601-scaled.jpg\",\"articleSection\":[\"Publicaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/\",\"url\":\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/\",\"name\":\"Miles de voces gritando \u201cApoyo. No castigo\u201d sacudieron la rambla del Raval - Metzineres\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/B1A9601-scaled.jpg\",\"datePublished\":\"2024-07-04T04:41:47+00:00\",\"dateModified\":\"2024-11-08T04:32:35+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/B1A9601-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/B1A9601-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/metzineres.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Miles de voces gritando \u201cApoyo. No castigo\u201d sacudieron la rambla del Raval\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/metzineres.org\\\/es\\\/\",\"name\":\"Metzineres\",\"description\":\"Entornos de cobijo para mujeres y personas de g\u00e9nero expansivo que sobreviven a m\u00faltiples violencias.\",\"publisher\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/metzineres.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#organization\",\"name\":\"Metzineres\",\"url\":\"http:\\\/\\\/metzineres.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-metzineres-negro.png\",\"contentUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-metzineres-negro.png\",\"width\":500,\"height\":151,\"caption\":\"Metzineres\"},\"image\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/person\\\/3eda218c9566f555577231b7402225e4\",\"name\":\"admin\",\"sameAs\":[\"https:\\\/\\\/metzineres.org\"],\"url\":\"https:\\\/\\\/metzineres.org\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miles de voces gritando \u201cApoyo. No castigo\u201d sacudieron la rambla del Raval - Metzineres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/","og_locale":"es_ES","og_type":"article","og_title":"Miles de voces gritando \u201cApoyo. No castigo\u201d sacudieron la rambla del Raval - Metzineres","og_description":"Por Sophia Vargas El mi\u00e9rcoles 26 de junio las Metzineres gritamos\u00a0\u201cApoyo. No castigo\u201d, en el marco del D\u00eda de Acci\u00f3n Global \u201cSupport Don&#8217;t Punish\u201d. Fue as\u00ed como la Rambla del Raval se convirti\u00f3 en un vibrante escenario de resistencia y solidaridad donde personas usuarias de drogas\u00a0abogamos por pol\u00edticas m\u00e1s humanas, enfocadas en la salud p\u00fablica [&hellip;]","og_url":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/","og_site_name":"Metzineres","article_published_time":"2024-07-04T04:41:47+00:00","article_modified_time":"2024-11-08T04:32:35+00:00","og_image":[{"width":2560,"height":1707,"url":"http:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/#article","isPartOf":{"@id":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/"},"author":{"name":"admin","@id":"http:\/\/metzineres.org\/es\/#\/schema\/person\/3eda218c9566f555577231b7402225e4"},"headline":"Miles de voces gritando \u201cApoyo. No castigo\u201d sacudieron la rambla del Raval","datePublished":"2024-07-04T04:41:47+00:00","dateModified":"2024-11-08T04:32:35+00:00","mainEntityOfPage":{"@id":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/"},"wordCount":628,"commentCount":0,"publisher":{"@id":"http:\/\/metzineres.org\/es\/#organization"},"image":{"@id":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/#primaryimage"},"thumbnailUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg","articleSection":["Publicaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/","url":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/","name":"Miles de voces gritando \u201cApoyo. No castigo\u201d sacudieron la rambla del Raval - Metzineres","isPartOf":{"@id":"http:\/\/metzineres.org\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/#primaryimage"},"image":{"@id":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/#primaryimage"},"thumbnailUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg","datePublished":"2024-07-04T04:41:47+00:00","dateModified":"2024-11-08T04:32:35+00:00","breadcrumb":{"@id":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/#primaryimage","url":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg","contentUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/B1A9601-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"http:\/\/metzineres.org\/es\/miles_de_voces_gritando_apoyo_no_castigo_sacudiero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/metzineres.org\/es\/"},{"@type":"ListItem","position":2,"name":"Miles de voces gritando \u201cApoyo. No castigo\u201d sacudieron la rambla del Raval"}]},{"@type":"WebSite","@id":"http:\/\/metzineres.org\/es\/#website","url":"http:\/\/metzineres.org\/es\/","name":"Metzineres","description":"Entornos de cobijo para mujeres y personas de g\u00e9nero expansivo que sobreviven a m\u00faltiples violencias.","publisher":{"@id":"http:\/\/metzineres.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/metzineres.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/metzineres.org\/es\/#organization","name":"Metzineres","url":"http:\/\/metzineres.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/metzineres.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/logo-metzineres-negro.png","contentUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/logo-metzineres-negro.png","width":500,"height":151,"caption":"Metzineres"},"image":{"@id":"http:\/\/metzineres.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/metzineres.org\/es\/#\/schema\/person\/3eda218c9566f555577231b7402225e4","name":"admin","sameAs":["https:\/\/metzineres.org"],"url":"https:\/\/metzineres.org\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/comments?post=107"}],"version-history":[{"count":3,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/107\/revisions"}],"predecessor-version":[{"id":648,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/107\/revisions\/648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media\/646"}],"wp:attachment":[{"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media?parent=107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/categories?post=107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/tags?post=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}