{"id":1223,"date":"2024-07-24T04:14:42","date_gmt":"2024-07-24T04:14:42","guid":{"rendered":"https:\/\/metzineres.org\/?p=1223"},"modified":"2024-11-08T04:16:00","modified_gmt":"2024-11-08T04:16:00","slug":"ofensiva_contra_los_clubes_cannabicos_un_retroceso","status":"publish","type":"post","link":"https:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/","title":{"rendered":"Ofensiva contra los clubes cann\u00e1bicos, un retroceso que atenta contra los derechos de las personas que usan cannabis y sus derivados"},"content":{"rendered":"<h4>Las Metzineres alzamos la voz contra el cierre de los clubes cann\u00e1bicos.<\/h4>\n<p>Las Metzineres nos oponemos firmemente a la decisi\u00f3n del Ayuntamiento de Barcelona que, con sus pol\u00edticas prohibicionistas y retr\u00f3gradas, ha sancionado econ\u00f3micamente y clausurado a distintos clubes sociales de cannabis (CSC) en la ciudad, poniendo en riesgo un modelo internacionalmente reconocido como una alternativa segura y responsable al mercado no regulado de cannabis.<\/p>\n<p>Los CSC funcionan en Barcelona desde hace m\u00e1s de 25 a\u00f1os. Desde aquel entonces se han ido consolidando como un lugar seguro para el consumo, ofreciendo informaci\u00f3n fiable a sus miembros, reduciendo los riesgos asociados al mercado no regulado y promoviendo un enfoque antiprohibicionista y libre de estigmas.<\/p>\n<p>La ecuaci\u00f3n es sencilla: el uso del cannabis no desaparecer\u00e1 prohibi\u00e9ndolo, su consumo seguir\u00e1 vigente pero trayendo consigo la criminalizaci\u00f3n, estigmatizaci\u00f3n y el favorecimiento de pol\u00edticas y pr\u00e1cticas violentas y abusivas contra nosotras<\/p>\n<p>Los CSC tienen la potencialidad de acompa\u00f1ar y favorecer una pol\u00edtica p\u00fablica enfocada a la mejora de la salud y el bienestar de las personas consumidoras y sus comunidades. Permiten un abordaje integral, que en nuestro caso contribuye a sobrellevar las situaciones de vulnerabilidad y sobrevivir las violencias que encaramos las mujerxs. Mientras en los clubs encontramos informaci\u00f3n objetiva y un espacio seguro que nos provee del apoyo necesario en caso de tener problemas relacionados con el consumo,\u00a0 el ayuntamiento nos criminaliza y obliga a recurrir a mercados ilegales y opacos.<\/p>\n<p>Mientras en pa\u00edses como Uruguay, Sud\u00e1frica, Malta y Alemania los CSC ya tienen un marco legal regulatorio, el Ayuntamiento de Barcelona toma la decisi\u00f3n arbitraria de retroceder. Sin atender a la robusta evidencia de los beneficios de este modelo pionero.<\/p>\n<p>Las Metzineres afirmamos que es urgente desarrollar pol\u00edticas sobre el uso de drogas que respeten los derechos humanos de las personas consumidoras y reparen los da\u00f1os que causa la prohibici\u00f3n y la criminalizaci\u00f3n, como la violencia de g\u00e9nero, el encarcelamiento y la injusticia econ\u00f3mica y social. Porque es imposible construir, a trav\u00e9s del prohibicionismo, una sociedad donde las causas estructurales de exclusi\u00f3n sean eliminadas y en la que todas tengamos derechos a una vida plena, digna y libre de violencias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Metzineres alzamos la voz contra el cierre de los clubes cann\u00e1bicos. Las Metzineres nos oponemos firmemente a la decisi\u00f3n del Ayuntamiento de Barcelona que, con sus pol\u00edticas prohibicionistas y retr\u00f3gradas, ha sancionado econ\u00f3micamente y clausurado a distintos clubes sociales de cannabis (CSC) en la ciudad, poniendo en riesgo un modelo internacionalmente reconocido como una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[],"class_list":["post-1223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ofensiva contra los clubes cann\u00e1bicos, un retroceso que atenta contra los derechos de las personas que usan cannabis y sus derivados - Metzineres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ofensiva contra los clubes cann\u00e1bicos, un retroceso que atenta contra los derechos de las personas que usan cannabis y sus derivados - Metzineres\" \/>\n<meta property=\"og:description\" content=\"Las Metzineres alzamos la voz contra el cierre de los clubes cann\u00e1bicos. Las Metzineres nos oponemos firmemente a la decisi\u00f3n del Ayuntamiento de Barcelona que, con sus pol\u00edticas prohibicionistas y retr\u00f3gradas, ha sancionado econ\u00f3micamente y clausurado a distintos clubes sociales de cannabis (CSC) en la ciudad, poniendo en riesgo un modelo internacionalmente reconocido como una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/\" \/>\n<meta property=\"og:site_name\" content=\"Metzineres\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-24T04:14:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T04:16:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/metzineres.org\/wp-content\/uploads\/2024\/11\/Web_ESP-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/person\\\/3eda218c9566f555577231b7402225e4\"},\"headline\":\"Ofensiva contra los clubes cann\u00e1bicos, un retroceso que atenta contra los derechos de las personas que usan cannabis y sus derivados\",\"datePublished\":\"2024-07-24T04:14:42+00:00\",\"dateModified\":\"2024-11-08T04:16:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/\"},\"wordCount\":407,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Web_ESP-scaled.jpg\",\"articleSection\":[\"Publicaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/\",\"url\":\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/\",\"name\":\"Ofensiva contra los clubes cann\u00e1bicos, un retroceso que atenta contra los derechos de las personas que usan cannabis y sus derivados - Metzineres\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Web_ESP-scaled.jpg\",\"datePublished\":\"2024-07-24T04:14:42+00:00\",\"dateModified\":\"2024-11-08T04:16:00+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Web_ESP-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Web_ESP-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/metzineres.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ofensiva contra los clubes cann\u00e1bicos, un retroceso que atenta contra los derechos de las personas que usan cannabis y sus derivados\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/metzineres.org\\\/es\\\/\",\"name\":\"Metzineres\",\"description\":\"Entornos de cobijo para mujeres y personas de g\u00e9nero expansivo que sobreviven a m\u00faltiples violencias.\",\"publisher\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/metzineres.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#organization\",\"name\":\"Metzineres\",\"url\":\"http:\\\/\\\/metzineres.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-metzineres-negro.png\",\"contentUrl\":\"https:\\\/\\\/metzineres.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-metzineres-negro.png\",\"width\":500,\"height\":151,\"caption\":\"Metzineres\"},\"image\":{\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/metzineres.org\\\/es\\\/#\\\/schema\\\/person\\\/3eda218c9566f555577231b7402225e4\",\"name\":\"admin\",\"sameAs\":[\"https:\\\/\\\/metzineres.org\"],\"url\":\"https:\\\/\\\/metzineres.org\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ofensiva contra los clubes cann\u00e1bicos, un retroceso que atenta contra los derechos de las personas que usan cannabis y sus derivados - Metzineres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/","og_locale":"es_ES","og_type":"article","og_title":"Ofensiva contra los clubes cann\u00e1bicos, un retroceso que atenta contra los derechos de las personas que usan cannabis y sus derivados - Metzineres","og_description":"Las Metzineres alzamos la voz contra el cierre de los clubes cann\u00e1bicos. Las Metzineres nos oponemos firmemente a la decisi\u00f3n del Ayuntamiento de Barcelona que, con sus pol\u00edticas prohibicionistas y retr\u00f3gradas, ha sancionado econ\u00f3micamente y clausurado a distintos clubes sociales de cannabis (CSC) en la ciudad, poniendo en riesgo un modelo internacionalmente reconocido como una [&hellip;]","og_url":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/","og_site_name":"Metzineres","article_published_time":"2024-07-24T04:14:42+00:00","article_modified_time":"2024-11-08T04:16:00+00:00","og_image":[{"width":2560,"height":1920,"url":"http:\/\/metzineres.org\/wp-content\/uploads\/2024\/11\/Web_ESP-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/#article","isPartOf":{"@id":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/"},"author":{"name":"admin","@id":"http:\/\/metzineres.org\/es\/#\/schema\/person\/3eda218c9566f555577231b7402225e4"},"headline":"Ofensiva contra los clubes cann\u00e1bicos, un retroceso que atenta contra los derechos de las personas que usan cannabis y sus derivados","datePublished":"2024-07-24T04:14:42+00:00","dateModified":"2024-11-08T04:16:00+00:00","mainEntityOfPage":{"@id":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/"},"wordCount":407,"commentCount":0,"publisher":{"@id":"http:\/\/metzineres.org\/es\/#organization"},"image":{"@id":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/#primaryimage"},"thumbnailUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/11\/Web_ESP-scaled.jpg","articleSection":["Publicaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/","url":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/","name":"Ofensiva contra los clubes cann\u00e1bicos, un retroceso que atenta contra los derechos de las personas que usan cannabis y sus derivados - Metzineres","isPartOf":{"@id":"http:\/\/metzineres.org\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/#primaryimage"},"image":{"@id":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/#primaryimage"},"thumbnailUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/11\/Web_ESP-scaled.jpg","datePublished":"2024-07-24T04:14:42+00:00","dateModified":"2024-11-08T04:16:00+00:00","breadcrumb":{"@id":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/#primaryimage","url":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/11\/Web_ESP-scaled.jpg","contentUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/11\/Web_ESP-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"http:\/\/metzineres.org\/es\/ofensiva_contra_los_clubes_cannabicos_un_retroceso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/metzineres.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ofensiva contra los clubes cann\u00e1bicos, un retroceso que atenta contra los derechos de las personas que usan cannabis y sus derivados"}]},{"@type":"WebSite","@id":"http:\/\/metzineres.org\/es\/#website","url":"http:\/\/metzineres.org\/es\/","name":"Metzineres","description":"Entornos de cobijo para mujeres y personas de g\u00e9nero expansivo que sobreviven a m\u00faltiples violencias.","publisher":{"@id":"http:\/\/metzineres.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/metzineres.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/metzineres.org\/es\/#organization","name":"Metzineres","url":"http:\/\/metzineres.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/metzineres.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/logo-metzineres-negro.png","contentUrl":"https:\/\/metzineres.org\/wp-content\/uploads\/2024\/05\/logo-metzineres-negro.png","width":500,"height":151,"caption":"Metzineres"},"image":{"@id":"http:\/\/metzineres.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/metzineres.org\/es\/#\/schema\/person\/3eda218c9566f555577231b7402225e4","name":"admin","sameAs":["https:\/\/metzineres.org"],"url":"https:\/\/metzineres.org\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/1223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/comments?post=1223"}],"version-history":[{"count":1,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/1223\/revisions"}],"predecessor-version":[{"id":1229,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/posts\/1223\/revisions\/1229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media\/1226"}],"wp:attachment":[{"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/media?parent=1223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/categories?post=1223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metzineres.org\/es\/wp-json\/wp\/v2\/tags?post=1223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}